{"id":2,"date":"2026-01-27T12:03:54","date_gmt":"2026-01-27T12:03:54","guid":{"rendered":"https:\/\/wonderful-ruby-elk.144-208-72-44.cpanel.site\/?page_id=2"},"modified":"2026-02-27T13:32:13","modified_gmt":"2026-02-27T13:32:13","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/quintadoscurubas.com\/en\/","title":{"rendered":"Welcome"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Explore<\/p>","protected":false},"excerpt":{"rendered":"Explore","protected":false},"author":1,"featured_media":15,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":1,"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":14,"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/pages\/2\/revisions\/14"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/media\/15"}],"wp:attachment":[{"href":"https:\/\/quintadoscurubas.com\/en\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}